{"id":72,"date":"2020-03-05T20:16:58","date_gmt":"2020-03-05T23:16:58","guid":{"rendered":"http:\/\/iro.org.br\/blog\/?p=72"},"modified":"2022-12-11T16:47:02","modified_gmt":"2022-12-11T19:47:02","slug":"a-tentacao-de-forjar-um-jesus-a-nossa-imagem-e-semelhanca","status":"publish","type":"post","link":"https:\/\/iro.org.br\/blog\/a-tentacao-de-forjar-um-jesus-a-nossa-imagem-e-semelhanca\/","title":{"rendered":"A Tenta\u00e7\u00e3o de forjar um Jesus \u00e0 nossa imagem e semelhan\u00e7a"},"content":{"rendered":"\n<blockquote class=\"wp-block-quote\"><p>\u00caxodo 32<\/p><p><sup>1<\/sup> Mas vendo o povo que Mois\u00e9s tardava em descer do monte, acercou-se de Ar\u00e3o, e disse-lhe: Levanta-te, faze-nos deuses, que v\u00e3o adiante de n\u00f3s; porque quanto a este Mois\u00e9s, o homem que nos tirou da terra do Egito, n\u00e3o sabemos o que lhe sucedeu.<\/p><p><sup>2<\/sup> E Ar\u00e3o lhes disse: Arrancai os pendentes de ouro, que est\u00e3o nas orelhas de vossas mulheres, e de vossos filhos, e de vossas filhas, e trazei-mos.<\/p><p><sup>3<\/sup> Ent\u00e3o todo o povo arrancou os pendentes de ouro, que estavam nas suas orelhas, e os trouxeram a Ar\u00e3o.<\/p><p><sup>4<\/sup> E ele os tomou das suas m\u00e3os, e trabalhou o ouro com um buril, e fez dele um bezerro de fundi\u00e7\u00e3o. Ent\u00e3o disseram: Este \u00e9 teu deus, \u00f3 Israel, que te tirou da terra do Egito. [&#8230;]<\/p><p><sup>7<\/sup> Ent\u00e3o disse o Senhor a Mois\u00e9s: Vai, desce; porque o teu povo, que fizeste subir do Egito, se tem corrompido,<\/p><p><sup>8<\/sup> E depressa se tem desviado do caminho que eu lhe tinha ordenado; eles fizeram para si um bezerro de fundi\u00e7\u00e3o, e perante ele se inclinaram, e ofereceram-lhe sacrif\u00edcios, e disseram: Este \u00e9 o teu deus, \u00f3 Israel, que te tirou da terra do Egito.<br><\/p><\/blockquote>\n\n\n\n<p>\u00c9 prov\u00e1vel que muitos dos leitores j\u00e1 tenham se deparado com esta passagem b\u00edblica e at\u00e9 mesmo se viram condenando igualmente o povo de Israel que, rec\u00e9m-sa\u00eddo do Egito no qual estavam em regime de escravid\u00e3o, viu obras miraculosas diretamente realizadas pelas m\u00e3os divinas e estava a caminho de uma terra \u201cprometida\u201d onde poderia repousar e nela edificar morada para si e suas gera\u00e7\u00f5es vindouras, tendo o Deus onipotente, onisciente e onipresente como centro de sua exist\u00eancia, legislador e guardi\u00e3o.<\/p>\n\n\n\n<p>Nosso intento aqui, neste breve texto, n\u00e3o \u00e9 fazer um exerc\u00edcio exeg\u00e9tico do evento narrado, nem mesmo atentarmo-nos detidamente para o evento em si e seu contexto hist\u00f3rico e geogr\u00e1fico maiores e menores, mas mostrar como tal atitude, quase compulsiva, de desviar-se da adora\u00e7\u00e3o verdadeira e sincera, \u00e9 uma tenta\u00e7\u00e3o recorrente, tendo afligido as gera\u00e7\u00f5es posteriores e perpetuando-se at\u00e9 nossos dias; de modo que deveria ser alvo de nossa constante observ\u00e2ncia para que n\u00e3o caiamos no mesmo erro. E, ainda que tenhamos ca\u00eddo, tenhamos de Deus miseric\u00f3rdia em Cristo para receber a ilumina\u00e7\u00e3o do Esp\u00edrito Santo, para que possamos ver nossos passos errados e voltarmo-nos para o caminho da simplicidade do Evangelho.<\/p>\n\n\n\n<p>A narrativa b\u00edblica em si \u00e9 clara e elucida o ocorrido com detalhes relevantes para compreens\u00e3o completa do evento. O povo israelita, insatisfeito com a demora de Mois\u00e9s (que intermediava junto ao povo e Deus) reclama a Ar\u00e3o que erija para toda a coletividade n\u00e3o somente um, mas v\u00e1rios deuses (apesar de o n\u00famero de deuses diante do ato id\u00f3latra n\u00e3o ser relevante ao caso, muito embora, seja demonstrativo da sede e a compuls\u00e3o que nutria o povo por adora\u00e7\u00e3o aos \u00eddolos). Ar\u00e3o, na aus\u00eancia de Mois\u00e9s, conclama os israelitas a agruparem-se a entregarem em suas m\u00e3os o ouro que possu\u00edssem. Uma vez em posse do ouro, fundiu um bezerro de ouro e anunciou ao povo: \u201cEste \u00e9 teu deus, \u00f3 Israel, que te tirou da terra do Egito\u201d, entregando um objeto para a sede id\u00f3latra do povo. \u00c9 curioso que a pr\u00f3pria imagem do bezerro, o animal bovino em si, servia de s\u00edmbolo para a imagem sagrada em representa\u00e7\u00e3o do deus eg\u00edpcio \u00c1pis, ligado \u00e0 fertilidade e \u00e0 terra. Apesar desta coincid\u00eancia e do fato de Israel ter sido recentemente retirado do Egito, n\u00e3o podemos ser levados \u00e0 conclus\u00e3o inequ\u00edvoca de que houve essa influ\u00eancia eg\u00edpcia na forja do bezerro pelos israelitas. A idolatria epis\u00f3dica do povo teve seu fim quando Mois\u00e9s desce do Monte por ordem divina e intercede pelo povo alcan\u00e7ando miseric\u00f3rdia.<\/p>\n\n\n\n<p>Esse \u00e9 apenas um dos relatos de idolatria que se pode verificar nas Escrituras, seja quando o pr\u00f3prio povo de Israel incorre em tal pr\u00e1tica ou quando povos vizinhos a promovem e incentivam, tais como a disputa entre Elias e os seguidores de Baal e os atos de renova\u00e7\u00e3o c\u00edvica e espiritual no reinado de Josias com a retirada de todos os \u00eddolos e altares com zelo \u00edmpar.<\/p>\n\n\n\n<p>O reformador genebrino Jo\u00e3o Calvino (1509\u20131564), em sua obra <em>Institutas da Religi\u00e3o Crist\u00e3<\/em>, argumenta que \u201co pensamento humano \u00e9, por assim dizer, uma eterna f\u00e1brica de \u00eddolos\u201d <cite>(Inst. I, 11, 8)<\/cite>. Na an\u00e1lise acurada do te\u00f3logo e reformador, a condi\u00e7\u00e3o humana agora, a partir de seu estado p\u00f3s-queda, est\u00e1 marcada por uma sede muitas vezes saciada por formas equivocadas e her\u00e9ticas de adora\u00e7\u00e3o e que leva a humanidade a se prostrar diante de \u00eddolos fabricados por suas pr\u00f3prias m\u00e3os, incapazes de fazer-lhes qualquer bem ou mostrar-lhes o caminho da salva\u00e7\u00e3o; pelo contr\u00e1rio, apenas revelam a deturpa\u00e7\u00e3o da natureza humana que busca em imagens, s\u00edmbolos e sentimentos suprir necessidades e circunst\u00e2ncias que somente podem ser direcionadas e supridas por Deus em Cristo na a\u00e7\u00e3o do Esp\u00edrito Santo. A humanidade muitas vezes forja \u00eddolos para lhe fornecerem a falsa seguran\u00e7a em face das conting\u00eancias cotidianas, do desespero, de suas expectativas, seus prop\u00f3sitos e necessidades.<\/p>\n\n\n\n<p>O pr\u00f3prio Cristo deparou-se com esta condi\u00e7\u00e3o humana quando indagou seus disc\u00edpulos sobre quem o povo acreditava que Ele seria. Apresentaram uma multiplicidade de respostas; alguns diziam ser Cristo Jo\u00e3o Batista, outros Elias e, um dentre os profetas. Somente Pedro apresentou Jesus como de fato ele era, \u00e9 e ser\u00e1 eternamente: \u201cTu \u00e9s o Cristo, o Filho do Deus Vivo\u201d <cite>(Mc. 8. 28\u201329; Mt. 16. 13\u201317)<\/cite>. Todas as demais vis\u00f5es sobre Cristo eram ou deturpa\u00e7\u00f5es ou fragmenta\u00e7\u00f5es, desejos e aspira\u00e7\u00f5es sobre quem desejavam que Cristo fosse para eles. Toda esta vis\u00e3o fragment\u00e1ria trazia aspira\u00e7\u00f5es e distor\u00e7\u00f5es sobre a realidade. Muitos n\u00e3o entenderam suas palavras, como quando se postou diante do povo e disse \u201cDerribai este templo, e em tr\u00eas dias o levantarei\u201d <cite>(Jo 2.19)<\/cite>; muitos o interpretaram literalmente, mas, na verdade, Cristo estava referindo-se ao templo de seu corpo, ao evento de sua ressurei\u00e7\u00e3o, central para teologia crist\u00e3 e para todo o crist\u00e3o ao demonstrar a vit\u00f3ria de Cristo sobre a morte.<\/p>\n\n\n\n<p>Tal incompreens\u00e3o e surdez se manifestam quando as analisamos \u00e0 luz das Escrituras, haja vista que o pr\u00f3prio profeta dito messi\u00e2nico, Isa\u00edas, havia pronunciado: \u201cVai, e dize a este povo: Ouvis, de fato, e n\u00e3o entendeis, e vedes, em verdade, mas n\u00e3o percebeis. Engorda o cora\u00e7\u00e3o deste povo, e faze-lhe pesados os ouvidos, e fecha-lhe os olhos; para que ele n\u00e3o veja com os seus olhos, e n\u00e3o ou\u00e7a com os seus ouvidos, nem entenda com o seu cora\u00e7\u00e3o, nem se converta e seja sarado\u201d <cite>(Is. 6.9\u201310)<\/cite>; \u201cQuem deu cr\u00e9dito \u00e0 nossa prega\u00e7\u00e3o? E a quem se manifestou o bra\u00e7o do Senhor?\u201d <cite>(Is. 53.1)<\/cite>.<\/p>\n\n\n\n<p>A real apreens\u00e3o de Jesus por parte de Pedro n\u00e3o se realizou por m\u00e9ritos pr\u00f3prios e fiados em sua estrita racionalidade; o pr\u00f3prio Cristo afirma que essa vigorosa confiss\u00e3o foi objeto de revela\u00e7\u00e3o, n\u00e3o \u201ca carne e o sangue, mas meu Pai, que est\u00e1 nos c\u00e9us\u201d <cite>(Mt. 16.17)<\/cite>. Cristo, o Filho do Deus vivo, isto \u00e9, sua apreens\u00e3o integral, n\u00e3o fragment\u00e1ria e\/ou deturpada foi avalizada como pedra fundamental para o estabelecimento e fortalecimento da igreja: \u201ce sobre esta pedra edificarei a minha igreja, e as portas do inferno n\u00e3o prevalecer\u00e3o contra ela\u201d <cite>(Mt. 16.18)<\/cite>. Compreender Cristo, sua igreja e seu fundamento dessa forma, sem deturpa\u00e7\u00f5es, fragmentos, ou vilipendiando-a de acordo com as paix\u00f5es humanas e suas utopias e desejos, \u00e9 fundamental para a perman\u00eancia da igreja nos moldes e simplicidade evang\u00e9licos.<\/p>\n\n\n\n<p>Hodiernamente, nossa tentativa humana de forjar \u00eddolos para nossa adora\u00e7\u00e3o permanece. Fragmentamos aspectos da realidade e os transformamos em refer\u00eancias \u00faltimas de nossas vidas; vivemos vidas forjadas por n\u00f3s mesmos em uma ilus\u00e3o de completude, mesmo tendo anulado qualquer aspecto de transcend\u00eancia de nossas vidas. Consumo, m\u00eddias e redes sociais, pol\u00edtica, economia, bem-estar a qualquer custo, viraram altares e \u00eddolos do e no cora\u00e7\u00e3o humano, nos quais todos sacrificam a si pr\u00f3prios ou aos seus mais \u00edntimos desejos id\u00f3latras. O pr\u00f3prio Cristo n\u00e3o foi isento de todo este despojo e deturpa\u00e7\u00e3o. Criaram-se \u201cCristos\u201d forjados ao bel-prazer da demanda da clientela do forjador. O Cristo socialista, Cristo liberal, Cristo conservador (n\u00e3o se preocupam com as anacronias ou com as indesculp\u00e1veis ou p\u00e9rfidas exegeses). Cristos que chancelam uma vida de consumo ou de espet\u00e1culo, na qual o crist\u00e3o pode fingir sua vida midi\u00e1tica e criar para si uma persona totalmente diferente da que deveria ser e, at\u00e9 mesmo, da persona que <em>\u00e9<\/em>, j\u00e1 que quase nunca se apresenta midiaticamente nas situa\u00e7\u00f5es cotidianas e comuns, mas sempre com uma alegria fugidia cuja efemeridade \u00e9 alimento para todos os \u201cseguidores\u201d. As m\u00eddias e redes sociais, para alguns crist\u00e3os, tornaram-se uma armadilha (o que \u00e9 lament\u00e1vel), pois n\u00e3o souberam lidar com as ferramentas advindas da gra\u00e7a comum divina para um uso e entretenimento sadios; antes, tem se transformado em um palco de belicosidade e apresenta\u00e7\u00e3o desses \u201cCristos\u201d forjados, em que cada um apresenta qual fragmento ou deturpa\u00e7\u00e3o (ou desejo \u00edntimo de seu forjador) \u00e9 mais consent\u00e2neo com uma realidade mais complexa que a maioria deles pode conceber.<\/p>\n\n\n\n<p>Infelizmente, pastores estudiosos e l\u00edderes t\u00eam se imiscu\u00eddo em tal idolatria, quando arvoram de sua titula\u00e7\u00e3o acad\u00eamica para menosprezar ou contrapor-se a outras pessoas em vez de apresentarem uma argumenta\u00e7\u00e3o crist\u00e3 s\u00f3lida e consistente; ou ainda transformarem seus sonhos, desejos, carreiras e curr\u00edculos de forma t\u00e3o gananciosa nesta forja de Hefesto que nem ainda alcan\u00e7aram seu intento e j\u00e1 tem a necessidade de anunciar aos \u201cseguidores\u201d que s\u00e3o candidatos a algo ou que pretendem fazer algo, como se necessitasse tocar trombetas a todo passo que dessem. \u00c9 uma triste realidade, pois estamos forjando \u201cCristos validadores\u201d ou legitimadores para todas as pr\u00e1ticas que temos como uma forma de fugirmos da necess\u00e1ria atitude de confrontar nossos pecados. Somos crist\u00e3os, por conseguinte, salvos em Cristo, mas nossa natureza pecaminosa bate \u00e0 nossa porta constantemente, mais que imaginamos.<\/p>\n\n\n\n<p>N\u00e3o podemos criar escapes ou fragmentar as Escrituras para fugir de nossos pecados ou da necessidade de encar\u00e1-los. N\u00e3o podemos fragmentar as Escrituras, o Logos divino, a Verdade encarnada para satisfazer nossas vontades mais \u00edntimas, pueris, s\u00f3rdidas ou at\u00e9 mesmo bem-intencionadas. N\u00e3o cabe a n\u00f3s interpretarmos e \u00e0 luz de nossas experi\u00eancias e vontades e sim nossos caminhos e desejos \u00e0 luz de Cristo, um Cristo vivo, integral, que n\u00e3o se deixa submeter \u00e0s muitas fragmenta\u00e7\u00f5es, relativismos ou absolutiza\u00e7\u00f5es hodiernas. \u00c9, pois, um Evangelho simples e puro, mas desfragmentado.<\/p>\n\n\n<hr>\n\n\n<p><strong>Thiago Moreira <\/strong>\u00e9 Doutor em Ci\u00eancia da Religi\u00e3o pela Universidade Federal de Juiz de Fora\/MG e membro da Igreja Reformada Ortodoxa.<\/p>\n\n\n\n<figcaption> Foto do post por&nbsp;<a href=\"https:\/\/unsplash.com\/@arturorey?utm_source=unsplash&amp;utm_medium=referral&amp;utm_content=creditCopyText\">Arturo Rey<\/a>&nbsp;no&nbsp;<a href=\"https:\/\/unsplash.com\/?utm_source=unsplash&amp;utm_medium=referral&amp;utm_content=creditCopyText\">Unsplash<\/a> <\/figcaption>\n","protected":false},"excerpt":{"rendered":"<p>Em nossa tentativa humana de forjar \u00eddolos, fragmentamos aspectos da realidade e os transformamos em refer\u00eancias \u00faltimas de nossas vidas. Criaram-se \u201cCristos\u201d forjados ao bel-prazer da demanda da clientela do forjador.<\/p>\n","protected":false},"author":4,"featured_media":94,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[18],"tags":[17,15,16],"acf":[],"_links":{"self":[{"href":"https:\/\/iro.org.br\/blog\/wp-json\/wp\/v2\/posts\/72"}],"collection":[{"href":"https:\/\/iro.org.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/iro.org.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/iro.org.br\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/iro.org.br\/blog\/wp-json\/wp\/v2\/comments?post=72"}],"version-history":[{"count":14,"href":"https:\/\/iro.org.br\/blog\/wp-json\/wp\/v2\/posts\/72\/revisions"}],"predecessor-version":[{"id":127,"href":"https:\/\/iro.org.br\/blog\/wp-json\/wp\/v2\/posts\/72\/revisions\/127"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iro.org.br\/blog\/wp-json\/wp\/v2\/media\/94"}],"wp:attachment":[{"href":"https:\/\/iro.org.br\/blog\/wp-json\/wp\/v2\/media?parent=72"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/iro.org.br\/blog\/wp-json\/wp\/v2\/categories?post=72"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/iro.org.br\/blog\/wp-json\/wp\/v2\/tags?post=72"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}